{"id":1000026178,"date":"2023-11-30T08:32:45","date_gmt":"2023-11-30T08:32:45","guid":{"rendered":"https:\/\/cocosolis.com\/pt\/?post_type=product&#038;p=1000026178"},"modified":"2026-07-09T13:53:25","modified_gmt":"2026-07-09T12:53:25","slug":"rose-clean-hydrate-face-foam","status":"publish","type":"product","link":"https:\/\/cocosolis.com\/pt\/product\/rose-clean-hydrate-face-foam\/","title":{"rendered":"ROSE Clean &amp; Hydrate Face Foam"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":1000004569,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[63],"product_tag":[],"product_template":[61],"class_list":{"0":"post-1000026178","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-face","7":"product_template-v-2024","9":"first","10":"instock","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/cocosolis.com\/pt\/wp-json\/wp\/v2\/product\/1000026178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cocosolis.com\/pt\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/cocosolis.com\/pt\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cocosolis.com\/pt\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/cocosolis.com\/pt\/wp-json\/wp\/v2\/media?parent=1000026178"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/cocosolis.com\/pt\/wp-json\/wp\/v2\/product_brand?post=1000026178"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/cocosolis.com\/pt\/wp-json\/wp\/v2\/product_cat?post=1000026178"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/cocosolis.com\/pt\/wp-json\/wp\/v2\/product_tag?post=1000026178"},{"taxonomy":"product_template","embeddable":true,"href":"https:\/\/cocosolis.com\/pt\/wp-json\/wp\/v2\/product_template?post=1000026178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}